{"id":2714,"date":"2020-10-16T18:27:03","date_gmt":"2020-10-16T17:27:03","guid":{"rendered":"https:\/\/vinodavani.org\/?p=2714"},"modified":"2022-02-11T14:31:32","modified_gmt":"2022-02-11T13:31:32","slug":"como-puedo-vivir-tranquilo","status":"publish","type":"post","link":"https:\/\/vinodavani.org\/es\/como-puedo-vivir-tranquilo\/","title":{"rendered":"\u00bfC\u00f3mo puedo vivir tranquilo?"},"content":{"rendered":"<div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-1 fusion-flex-container nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row fusion-flex-align-items-flex-start fusion-flex-content-wrap\" style=\"max-width:1144px;margin-left: calc(-4% \/ 2 );margin-right: calc(-4% \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-0 fusion_builder_column_1_1 1_1 fusion-flex-column\" style=\"--awb-bg-size:cover;--awb-width-large:100%;--awb-margin-top-large:0px;--awb-spacing-right-large:1.92%;--awb-margin-bottom-large:20px;--awb-spacing-left-large:1.92%;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-text fusion-text-1\"><p><img decoding=\"async\" class=\"alignnone size-full wp-image-2707\" src=\"https:\/\/vinodavani.org\/wp-content\/uploads\/2020\/10\/02-VVSA-featured-photo-600x338-1.jpg\" alt=\"\" width=\"600\" height=\"338\" srcset=\"https:\/\/vinodavani.org\/wp-content\/uploads\/2020\/10\/02-VVSA-featured-photo-600x338-1-200x113.jpg 200w, https:\/\/vinodavani.org\/wp-content\/uploads\/2020\/10\/02-VVSA-featured-photo-600x338-1-400x225.jpg 400w, https:\/\/vinodavani.org\/wp-content\/uploads\/2020\/10\/02-VVSA-featured-photo-600x338-1.jpg 600w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/p>\n<p>\u00bfC\u00f3mo puedo vivir tranquilo?<\/p>\n<p>En primer lugar, muchas gracias por tu pregunta. Esa es una pregunta muy com\u00fan y tambi\u00e9n muy importante. Espero que la respuesta no resulte tan desanimante, simplemente se responde:<\/p>\n<p>\u00a1No podemos vivir tranquilamente!<\/p>\n<p>A pesar de este hecho, la pregunta sigue siendo v\u00e1lida e importante. Podemos tratar de comprender qu\u00e9 es la calma, qu\u00e9 nos molesta y si la calma es realmente algo deseable.<\/p>\n<p>Solo podemos hacer preguntas desde nuestra perspectiva y experiencia actuales. Lo que estamos experimentando ahora es el malestar, este malestar es subjetivo y es causado por circunstancias internas y externas. La \u201cvida\u201d en realidad puede tomarse como sin\u00f3nimo de malestar; Cuando hay vida no hay descanso.<\/p>\n<p>Imagina una fiesta privada en un apartamento: Los participantes de la fiesta disfrutan de la m\u00fasica a todo volumen, pero los vecinos se sienten molestos al mismo tiempo. Lo mismo, la m\u00fasica en este caso, puede ser motivo de alegr\u00eda y perturbaci\u00f3n. Ambas experiencias son disturbios, uno se experimenta como agradable y el otro como desagradable.<\/p>\n<p>Otro ejemplo ser\u00eda la lluvia: Imagina el anhelo de lluvia del agricultor cuando ha habido una sequ\u00eda durante mucho tiempo. Por otro lado, imagina las preocupaciones de un organizador de eventos importantes que ha planeado un evento al aire libre. Si llueve, traer\u00e1 alegr\u00eda al agricultor y preocupaci\u00f3n al organizador. En ausencia de lluvia, ocurrir\u00eda lo contrario. Sin embargo, si estuviera nublado y pareciera que iba a llover, entonces ambos estar\u00edan tensos con sus expectativas y temores y solo con el transcurso del tiempo quedar\u00eda claro con qui\u00e9n \u201cel destino o los dioses fueron m\u00e1s misericordiosos\u201d.<\/p>\n<p>La vida est\u00e1 llena de infinidad de circunstancias y experiencias que, tomadas en su conjunto, nos dejan con un sentimiento de satisfacci\u00f3n o insatisfacci\u00f3n condicionada. Alguien que est\u00e1 m\u00e1s insatisfecho en la vida piensa en el descanso como una especie de liberaci\u00f3n, o igual de la ausencia de inquietudes y sus causas. Por otro lado, las personas felices y agradables percibir\u00edan la calma como una ausencia de las causas de su felicidad.<\/p>\n<p>Puede pensar en ello como el saldo \u201c0\u201d de una cuenta bancaria. El saldo \u00ab0\u00bb es muy deseable para alguien que est\u00e1 estrangulado por las deudas, mientras que para alguien que est\u00e1 gastando dinero es la p\u00e9rdida de toda su capacidad adquisitiva.<\/p>\n<p>De esta forma se podr\u00eda simplificar la experiencia de la dualidad del mundo material.<\/p>\n<p>\u00bfQu\u00e9 depende ahora de si est\u00e1s de un lado o del otro, si la vida significa \u00abbueno o malo\u00bb para ti? Este estado se llama Karma. El karma puede entenderse tanto como una acci\u00f3n como como resultado de la acci\u00f3n. En nuestro ejemplo, el balance de ahorros o deudas ser\u00eda el resultado de nuestras acciones anteriores.<\/p>\n<p>Las acciones no son solo acciones, se componen de acciones e intenciones que juntas determinan el karma futuro como resultado. En t\u00e9rminos simples, se puede decir que las actividades que se dedican al bien com\u00fan crean un buen karma, y las actividades que surgen de intenciones ego\u00edstas traen mal karma o circunstancias negativas en el futuro. De esta manera, puedes entender por qu\u00e9 dice el viejo refr\u00e1n: \u201cCada uno es el hacedor de su propia felicidad\u201d. No hay circunstancias en la vida que no hayamos causado nosotros mismos a trav\u00e9s de nuestras acciones. Esto es cierto incluso si ya no recordamos o reconocemos las conexiones y los puntos en el tiempo, porque estos pueden estar dispersos a trav\u00e9s de diferentes encarnaciones para complicar a\u00fan m\u00e1s el enigma de la vida y la existencia.<\/p>\n<p>El karma que experimentamos en las circunstancias actuales como resultado de nuestras acciones en el pasado es importante porque tenemos que aprender a comprenderlo y aceptarlo, porque solo as\u00ed nos damos cuenta de lo importante que es lo que hacemos despu\u00e9s de esto. Es cosa de tiempo. El karma como acci\u00f3n en el ahora es directamente la causa del karma como circunstancia en el futuro.<\/p>\n<p>Uno puede volverse alcoh\u00f3lico, o degradarse de alguna otra manera en la vida, en la que uno consume los resultados del buen karma en forma de herencia, o en la que lo crea a partir de deudas y mediante nuevas deudas.<\/p>\n<p>El karma bueno y malo como circunstancia actual de la vida no solo se puede medir en t\u00e9rminos de apoyo financiero. Es una combinaci\u00f3n de varios aspectos, como el social, familiar y sobre todo el apoyo en los propios valores y el car\u00e1cter de una persona.<\/p>\n<p>Uno solo puede ser una persona con un car\u00e1cter fuerte si est\u00e1 decidido a superar la dualidad del mundo material. Para hacer esto, uno tiene que buscar la conexi\u00f3n con la trascendencia. El descanso no ayuda mucho. Dedicarse al ideal trascendental, tanto en las buenas como en las malas, requiere una fe fuerte. Circunstancias materiales o karm\u00e1ticas como inteligencia, poder, dinero, etc., tanto en su presencia como en su ausencia, no pueden ser de ayuda ni representar un obst\u00e1culo en este camino.<\/p>\n<p>Por eso, el camino de la fe es algo natural en la vida, mientras que la b\u00fasqueda del descanso es y sigue siendo algo abstracto y confuso, como lo es el intento de gozar de la felicidad, que no se puede separar del sufrimiento.<\/p>\n<p>Por tanto, debemos distinguir la calma, de la Paz. No hay descanso porque todo, todo el universo est\u00e1 en constante movimiento, lo que crea nuevas circunstancias y experiencias karm\u00e1ticas.<\/p>\n<p>Finalmente, quisiera citar la \u201cOraci\u00f3n por la serenidad, el coraje y la sabidur\u00eda\u201d de Reinhold Niebuhr, en la que refleja muy claramente la actitud a trav\u00e9s de la cual podemos lograr la Paz.<\/p>\n<p style=\"text-align: center;\"><em>\u201cDios dame la serenidad para aceptar cosas que no puedo cambiar<\/em><br \/>\n<em>el coraje para cambiar cosas que puedo cambiar<\/em><br \/>\n<em>y la sabidur\u00eda para distinguir unos de otros.\u201d<\/em><\/p>\n<p>Muchos secretos y respuestas se esconden en la Fe.<\/p>\n<\/div><\/div><\/div><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":6,"featured_media":2710,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[52],"tags":[],"_links":{"self":[{"href":"https:\/\/vinodavani.org\/es\/wp-json\/wp\/v2\/posts\/2714"}],"collection":[{"href":"https:\/\/vinodavani.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/vinodavani.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/vinodavani.org\/es\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/vinodavani.org\/es\/wp-json\/wp\/v2\/comments?post=2714"}],"version-history":[{"count":4,"href":"https:\/\/vinodavani.org\/es\/wp-json\/wp\/v2\/posts\/2714\/revisions"}],"predecessor-version":[{"id":2733,"href":"https:\/\/vinodavani.org\/es\/wp-json\/wp\/v2\/posts\/2714\/revisions\/2733"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/vinodavani.org\/es\/wp-json\/wp\/v2\/media\/2710"}],"wp:attachment":[{"href":"https:\/\/vinodavani.org\/es\/wp-json\/wp\/v2\/media?parent=2714"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/vinodavani.org\/es\/wp-json\/wp\/v2\/categories?post=2714"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/vinodavani.org\/es\/wp-json\/wp\/v2\/tags?post=2714"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}